{"id":3831,"date":"2025-11-25T04:46:17","date_gmt":"2025-11-25T04:46:17","guid":{"rendered":"https:\/\/cityplaza.or.jp\/wp2024\/?post_type=xo_event&#038;p=3831"},"modified":"2025-11-25T04:46:18","modified_gmt":"2025-11-25T04:46:18","slug":"airsis_03","status":"publish","type":"xo_event","link":"https:\/\/cityplaza.or.jp\/wp2024\/index.php\/xo_event\/airsis_03\/","title":{"rendered":"\u77ed\u7e2e\u55b6\u696d"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","xo_event_cat":[13],"class_list":["post-3831","xo_event","type-xo_event","status-publish","hentry","xo_event_cat-13"],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/cityplaza.or.jp\/wp2024\/index.php\/wp-json\/wp\/v2\/xo_event\/3831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cityplaza.or.jp\/wp2024\/index.php\/wp-json\/wp\/v2\/xo_event"}],"about":[{"href":"https:\/\/cityplaza.or.jp\/wp2024\/index.php\/wp-json\/wp\/v2\/types\/xo_event"}],"wp:attachment":[{"href":"https:\/\/cityplaza.or.jp\/wp2024\/index.php\/wp-json\/wp\/v2\/media?parent=3831"}],"wp:term":[{"taxonomy":"xo_event_cat","embeddable":true,"href":"https:\/\/cityplaza.or.jp\/wp2024\/index.php\/wp-json\/wp\/v2\/xo_event_cat?post=3831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}